{"id":1877,"date":"2019-07-08T13:57:30","date_gmt":"2019-07-08T17:57:30","guid":{"rendered":"https:\/\/pausspa.ca\/sherbrooke\/?p=1877"},"modified":"2019-07-08T14:02:44","modified_gmt":"2019-07-08T18:02:44","slug":"1877","status":"publish","type":"post","link":"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/","title":{"rendered":"Article \u00ab\u00a0D\u00e9tente foodie\u00a0\u00bb par Nana Toulouse"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_mi_skip_tracking":false},"categories":[27],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Article &quot;D\u00e9tente foodie&quot; par Nana Toulouse - Sherbrooke<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Article &quot;D\u00e9tente foodie&quot; par Nana Toulouse - Sherbrooke\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/\" \/>\n<meta property=\"og:site_name\" content=\"Sherbrooke\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-08T17:57:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-08T18:02:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pausspa.ca\/sherbrooke\/wp-content\/uploads\/sites\/2\/2018\/03\/paus-OGimage_2-3.png\" \/>\n<meta name=\"author\" content=\"jnoel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jnoel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/\",\"url\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/\",\"name\":\"Article \\\"D\u00e9tente foodie\\\" par Nana Toulouse - Sherbrooke\",\"isPartOf\":{\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/#website\"},\"datePublished\":\"2019-07-08T17:57:30+00:00\",\"dateModified\":\"2019-07-08T18:02:44+00:00\",\"author\":{\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/#\/schema\/person\/134d49583e0e9dc360be980edbd52e19\"},\"breadcrumb\":{\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Article \u00ab\u00a0D\u00e9tente foodie\u00a0\u00bb par Nana Toulouse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/#website\",\"url\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/\",\"name\":\"Sherbrooke\",\"description\":\"Un site utilisant PA\u016aS Spa sites Web\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/#\/schema\/person\/134d49583e0e9dc360be980edbd52e19\",\"name\":\"jnoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c52cc739582734970ea27809d986f307?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c52cc739582734970ea27809d986f307?s=96&d=mm&r=g\",\"caption\":\"jnoel\"},\"url\":\"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/author\/jnoel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Article \"D\u00e9tente foodie\" par Nana Toulouse - Sherbrooke","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Article \"D\u00e9tente foodie\" par Nana Toulouse - Sherbrooke","og_url":"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/","og_site_name":"Sherbrooke","article_published_time":"2019-07-08T17:57:30+00:00","article_modified_time":"2019-07-08T18:02:44+00:00","og_image":[{"url":"https:\/\/pausspa.ca\/sherbrooke\/wp-content\/uploads\/sites\/2\/2018\/03\/paus-OGimage_2-3.png"}],"author":"jnoel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jnoel"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/","url":"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/","name":"Article \"D\u00e9tente foodie\" par Nana Toulouse - Sherbrooke","isPartOf":{"@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/#website"},"datePublished":"2019-07-08T17:57:30+00:00","dateModified":"2019-07-08T18:02:44+00:00","author":{"@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/#\/schema\/person\/134d49583e0e9dc360be980edbd52e19"},"breadcrumb":{"@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/medias\/1877\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pausspa.ca\/sherbrooke\/fr\/"},{"@type":"ListItem","position":2,"name":"Article \u00ab\u00a0D\u00e9tente foodie\u00a0\u00bb par Nana Toulouse"}]},{"@type":"WebSite","@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/#website","url":"https:\/\/pausspa.ca\/sherbrooke\/fr\/","name":"Sherbrooke","description":"Un site utilisant PA\u016aS Spa sites Web","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pausspa.ca\/sherbrooke\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/#\/schema\/person\/134d49583e0e9dc360be980edbd52e19","name":"jnoel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pausspa.ca\/sherbrooke\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c52cc739582734970ea27809d986f307?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c52cc739582734970ea27809d986f307?s=96&d=mm&r=g","caption":"jnoel"},"url":"https:\/\/pausspa.ca\/sherbrooke\/fr\/articles\/author\/jnoel\/"}]}},"_links":{"self":[{"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/posts\/1877"}],"collection":[{"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/comments?post=1877"}],"version-history":[{"count":6,"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/posts\/1877\/revisions"}],"predecessor-version":[{"id":1884,"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/posts\/1877\/revisions\/1884"}],"wp:attachment":[{"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/media?parent=1877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/categories?post=1877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pausspa.ca\/sherbrooke\/fr\/wp-json\/wp\/v2\/tags?post=1877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}